{"id":662418,"date":"2020-01-23T11:27:57","date_gmt":"2020-01-23T10:27:57","guid":{"rendered":"https:\/\/shop.puntouno.it\/areatest\/?page_id=662418"},"modified":"2022-08-29T10:28:51","modified_gmt":"2022-08-29T08:28:51","slug":"spedizioni-e-resi","status":"publish","type":"page","link":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/","title":{"rendered":"Spedizioni e Resi"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<h3><strong>Tempi di Consegna<\/strong><\/h3>\n<p>[\/vc_column_text]<div id=\"porto-icon-10702472576a57344189dac\" class=\"porto-just-icon-wrapper  vc_custom_1580387304206\" style=\"text-align:left;\"><div class=\"porto-sicon-img \" style=\"display:inline-block;font-size: 64px;\"><img class=\"img-icon\" alt=\"\" src=\"https:\/\/shop.puntouno.it\/areatest\/wp-content\/uploads\/2020\/01\/delivery_3432.png\" width=\"128\" height=\"128\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Consegna con corriere espresso entro 3 giorni lavorativi (isole 4\/5 giorni lavorativi) dal ricevimento del pagamento.<\/p>\n<p>Per i pagamenti ricevuti dopo le ore 12.00 gli ordini verranno spediti il giorno lavorativo successivo.<\/p>\n<p>Per il pagamento in contrassegno l&#8217;ordine verr\u00e0 spedito il giorno lavorativo successivo se effettuato dopo le ore 12.00.[\/vc_column_text][\/vc_column][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<h3><strong>Spese di trasporto<\/strong><\/h3>\n<p>[\/vc_column_text]<div id=\"porto-icon-13547954806a5734418a29c\" class=\"porto-just-icon-wrapper  vc_custom_1580387533992\" style=\"text-align:left;\"><div class=\"porto-sicon-img \" style=\"display:inline-block;font-size: 64px;\"><img class=\"img-icon\" alt=\"\" src=\"https:\/\/shop.puntouno.it\/areatest\/wp-content\/uploads\/2020\/01\/cost.png\" width=\"512\" height=\"512\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Per le spedizioni in tutta Italia, isole comprese, il costo \u00e8 di \u20ac 15 + iva.<\/p>\n<p>Spedizione GRATIS per ordini di importo pari o superiore a \u20ac 300,00 +iva.[\/vc_column_text][\/vc_column][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<h3><strong>Ritiro in sede<\/strong><\/h3>\n<p>[\/vc_column_text]<div id=\"porto-icon-6439532956a5734418a44f\" class=\"porto-just-icon-wrapper  vc_custom_1580387533992\" style=\"text-align:left;\"><div class=\"porto-sicon-img \" style=\"display:inline-block;font-size: 64px;\"><img class=\"img-icon\" alt=\"\" src=\"https:\/\/shop.puntouno.it\/areatest\/wp-content\/uploads\/2020\/01\/cost.png\" width=\"512\" height=\"512\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Puoi pagare e ritirare il tuo ordine presso il nostro magazzino di Pescia (PT).<\/p>\n<p>Se hai scelto la modalit\u00e0 &#8220;Pagamento al ritiro&#8221;, hai a disposizione 3 giorni per ritirare l&#8217;ordine. Trascorso questo termine il tuo ordine verr\u00e0 annullato.<\/p>\n<p>Se hai necessit\u00e0, puoi ritirare il tuo ordine dopo i 3 giorni\u00a0depositando un acconto del 30%. Contatta il nostro Customer Service per maggiori informazioni a onlinestore@puntouno.it oppure al numero\u00a00572\/453452.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<h3><strong>Verifica gli imballaggi<\/strong><\/h3>\n<p>[\/vc_column_text]<div id=\"porto-icon-15104097706a5734418a945\" class=\"porto-just-icon-wrapper  vc_custom_1580389032177\" style=\"text-align:left;\"><div class=\"porto-sicon-img \" style=\"display:inline-block;font-size: 64px;\"><img class=\"img-icon\" alt=\"\" src=\"https:\/\/shop.puntouno.it\/areatest\/wp-content\/uploads\/2020\/01\/box-ok.png\" width=\"512\" height=\"512\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]All\u2019arrivo della merce apponi sulla lettera di vettura la dicitura\u00a0\u201c<strong>ACCETTO CON RISERVA DI CONTROLLO<\/strong>\u201d\u00a0e falla controfirmare dal corriere.<\/p>\n<p>Qualora ci fossero danni evidenti (merce danneggiata, sbancalata, o cartoni aperti, schiacciati o danneggiati) fai una foto ed inviacela.<\/p>\n<p><strong>Il danno sar\u00e0 rimborsato solo se la merce sar\u00e0 stata accettata con riserva<\/strong>.[\/vc_column_text][\/vc_column][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<h3><strong>Spedizioni internazionali<\/strong><\/h3>\n<p>[\/vc_column_text]<div id=\"porto-icon-5081025796a5734418acdd\" class=\"porto-just-icon-wrapper  vc_custom_1580389099143\" style=\"text-align:left;\"><div class=\"porto-sicon-img \" style=\"display:inline-block;font-size: 64px;\"><img class=\"img-icon\" alt=\"\" src=\"https:\/\/shop.puntouno.it\/areatest\/wp-content\/uploads\/2020\/01\/4047342-air-aircraft-airline-airliner-airplane-airport-airway_113505.png\" width=\"512\" height=\"512\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Per le spedizioni internazionali le spese e le modalit\u00e0 di consegna vi verranno comunicate dal nostro customer service in seguito al ricevimento dell&#8217;ordine.[\/vc_column_text][\/vc_column][vc_column][vc_separator][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<h3><strong>Resi<\/strong><\/h3>\n<p>[\/vc_column_text]<div id=\"porto-icon-13224514626a5734418b5bf\" class=\"porto-just-icon-wrapper  vc_custom_1631604276088\" style=\"text-align:left;\"><div class=\"porto-sicon-img \" style=\"display:inline-block;font-size: 64px;\"><img class=\"img-icon\" alt=\"\" src=\"https:\/\/shop.puntouno.it\/areatest\/wp-content\/uploads\/2021\/09\/reso1.png\" width=\"200\" height=\"200\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Non si accettano cambi, sostituzioni e resi di merce. Qualora la merce ricevuta fosse <strong>difettosa<\/strong> contattaci entro otto giorni dalla consegna allegando le foto. Il nostro customer service \u00e8 a tua disposizione![\/vc_column_text][\/vc_column][vc_column][vc_separator][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text] Tempi di Consegna [\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Consegna con corriere espresso entro 3 giorni lavorativi (isole 4\/5 giorni lavorativi) dal ricevimento del pagamento. Per i pagamenti ricevuti dopo le ore 12.00 gli ordini verranno spediti il giorno lavorativo successivo. Per il pagamento in contrassegno l&#8217;ordine verr\u00e0 spedito il giorno lavorativo successivo se effettuato dopo le ore [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Spedizioni e Resi - PuntoUno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spedizioni e Resi - PuntoUno\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text] Tempi di Consegna [\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Consegna con corriere espresso entro 3 giorni lavorativi (isole 4\/5 giorni lavorativi) dal ricevimento del pagamento. Per i pagamenti ricevuti dopo le ore 12.00 gli ordini verranno spediti il giorno lavorativo successivo. Per il pagamento in contrassegno l&#8217;ordine verr\u00e0 spedito il giorno lavorativo successivo se effettuato dopo le ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/\" \/>\n<meta property=\"og:site_name\" content=\"PuntoUno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/puntounopescia?_ga=2.146912823.1231967447.1686756641-1531453469.1686320315\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-29T08:28:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/\",\"url\":\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/\",\"name\":\"Spedizioni e Resi - PuntoUno\",\"isPartOf\":{\"@id\":\"https:\/\/shop.puntouno.it\/areatest\/#website\"},\"datePublished\":\"2020-01-23T10:27:57+00:00\",\"dateModified\":\"2022-08-29T08:28:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/shop.puntouno.it\/areatest\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spedizioni e Resi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/shop.puntouno.it\/areatest\/#website\",\"url\":\"https:\/\/shop.puntouno.it\/areatest\/\",\"name\":\"PuntoUno\",\"description\":\"Webshop\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/shop.puntouno.it\/areatest\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spedizioni e Resi - PuntoUno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/","og_locale":"it_IT","og_type":"article","og_title":"Spedizioni e Resi - PuntoUno","og_description":"[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text] Tempi di Consegna [\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Consegna con corriere espresso entro 3 giorni lavorativi (isole 4\/5 giorni lavorativi) dal ricevimento del pagamento. Per i pagamenti ricevuti dopo le ore 12.00 gli ordini verranno spediti il giorno lavorativo successivo. Per il pagamento in contrassegno l&#8217;ordine verr\u00e0 spedito il giorno lavorativo successivo se effettuato dopo le ore [&hellip;]","og_url":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/","og_site_name":"PuntoUno","article_publisher":"https:\/\/www.facebook.com\/puntounopescia?_ga=2.146912823.1231967447.1686756641-1531453469.1686320315","article_modified_time":"2022-08-29T08:28:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/","url":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/","name":"Spedizioni e Resi - PuntoUno","isPartOf":{"@id":"https:\/\/shop.puntouno.it\/areatest\/#website"},"datePublished":"2020-01-23T10:27:57+00:00","dateModified":"2022-08-29T08:28:51+00:00","breadcrumb":{"@id":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/shop.puntouno.it\/areatest\/spedizioni-e-resi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.puntouno.it\/areatest\/"},{"@type":"ListItem","position":2,"name":"Spedizioni e Resi"}]},{"@type":"WebSite","@id":"https:\/\/shop.puntouno.it\/areatest\/#website","url":"https:\/\/shop.puntouno.it\/areatest\/","name":"PuntoUno","description":"Webshop","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.puntouno.it\/areatest\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/pages\/662418"}],"collection":[{"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/comments?post=662418"}],"version-history":[{"count":0,"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/pages\/662418\/revisions"}],"wp:attachment":[{"href":"https:\/\/shop.puntouno.it\/areatest\/wp-json\/wp\/v2\/media?parent=662418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}